{"id":9333,"date":"2017-12-14T18:43:01","date_gmt":"2017-12-14T18:43:01","guid":{"rendered":"https:\/\/www.uta.cl\/camplus-de-la-uta-seleccionado-entre-las-iniciativas-mas-innovadoras-de\/web\/2017-12-14\/184301.html"},"modified":"2017-12-14T18:43:01","modified_gmt":"2017-12-14T18:43:01","slug":"camplus-de-la-uta-seleccionado-entre-las-iniciativas-mas-innovadoras-de","status":"publish","type":"post","link":"https:\/\/www.uta.cl\/index.php\/2017\/12\/14\/camplus-de-la-uta-seleccionado-entre-las-iniciativas-mas-innovadoras-de\/","title":{"rendered":"CAMPLUS de la UTA seleccionado entre las iniciativas m\u00e1s innovadoras de BIM en Am\u00e9rica Latina"},"content":{"rendered":"\n<p style=\"text-align: justify;\"><img loading=\"lazy\" alt=\"Imagen foto_00000002\" class=\"fotodrag\" height=\"187\" id=\"foto_00000002\" src=\"\/web\/site\/artic\/20171214\/imag\/foto_0000000220171214184301.jpg\" style=\"float: right; margin-left: 10px; margin-right: 10px;\" width=\"359\" data-w=\"550\" data-h=\"287\" \/>El Congreso Latinoamericano BIMLATAM 2017 seleccion\u00f3 las experiencias m\u00e1s innovadoras de Am\u00e9rica Latina en la aplicaci\u00f3n avanzada de la metodolog\u00eda BIM (Building Information Modeling). Las ponencias seleccionadas se expusieron el mes pasado durante el &#8220;Tercer Congreso Latinoamericano BIM LATAM 2017&#8221; realizado en Santiago. Este a\u00f1o el congreso focaliz\u00f3 su selecci\u00f3n en ponencias de vanguardia e innovaci\u00f3n en BIM para la Cuarta Revoluci\u00f3n Industrial conocida como Industria 4.0. La metodolog\u00eda BIM eleva la productividad y eficiencia en el sector de la construcci\u00f3n y por tal motivo distintos pa\u00edses incluido Chile han adoptado recientemente dicha metodolog\u00eda.<\/p>\n<p style=\"text-align: justify;\">La Dra. Claudia Vicentelo Lupa present\u00f3 &#8220;CAMPLUS Big Data: Spatial Planning Information Modeling (SPIM) in Knowledge Planning&#8221; que mediante la metodolog\u00eda SPIM es una evoluci\u00f3n de BIM desde la edificaci\u00f3n hacia la escala espacial, con el uso masivo de datos denominado big data. Tambi\u00e9n se present\u00f3 el &#8220;Modelamiento 3D de la Matriz Energ\u00e9tica Inteligente&#8221; que propone la Ciudad del Conocimiento de CAMPLUS. Esta presentaci\u00f3n fue realizada por el ingeniero Stavros Kukulis Mart\u00ednez, quien expuso los alcances y an\u00e1lisis de la Matriz Energ\u00e9tica Inteligente de CAMPLUS que permite una transformaci\u00f3n &#8220;from policies to practices&#8221; basada en la nueva pol\u00edtica energ\u00e9tica 2050 de nuestro pa\u00eds.<\/p>\n<table border=\"0\" style=\"border-spacing: 10px;\">\n<tbody>\n<tr>\n<td><img loading=\"lazy\" alt=\"Imagen foto_00000004\" border=\"0\" class=\"fotodrag\" height=\"244\" id=\"foto_00000004\" src=\"\/web\/site\/artic\/20171214\/imag\/foto_0000000420171214184301.jpg\" width=\"326\" data-w=\"550\" data-h=\"413\" \/><\/td>\n<td><img loading=\"lazy\" alt=\"Imagen foto_00000001\" border=\"0\" class=\"fotodrag\" height=\"245\" id=\"foto_00000001\" src=\"\/web\/site\/artic\/20171214\/imag\/foto_0000000120171214184301.jpg\" width=\"369\" data-w=\"550\" data-h=\"364\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\"><strong>Campus universitario inteligente para el siglo XXI<\/strong><\/p>\n<p style=\"text-align: justify;\">La Dra. Vicentelo precis\u00f3 que CAMPLUS es la planificaci\u00f3n de un Campus universitario inteligente para el siglo XXI, con visi\u00f3n de futuro. Para lo cual se utiliz\u00f3 la metodolog\u00eda SPIM en Knowledge Planning (planificaci\u00f3n basada en el conocimiento) y es una contribuci\u00f3n a la disciplina de la planificaci\u00f3n territorial e innovaci\u00f3n en la metodolog\u00eda BIM realizada en el LAB-ICT (Laboratorio de Innovaci\u00f3n y Ciencias del Territorio) de la Universidad de Tarapac\u00e1. Adem\u00e1s la planificaci\u00f3n espacial avanzada aplicada en CAMPLUS es posible que sea utilizada en diferentes escalas espaciales tales como: barrio, distrito industrial, ciudad o regi\u00f3n.<\/p>\n<p style=\"text-align: justify;\">En el Tercer Congreso BIMLATAM 2017 caus\u00f3 gran inter\u00e9s el alto nivel de la planificaci\u00f3n espacial avanzada e innovaci\u00f3n de CAMPLUS el &#8220;Plan Maestro del Campus Saucache 2030: Ciudad del Conocimiento, Inteligente y Sostenible&#8221;. As\u00ed lo manifestaron representantes del sector p\u00fablico y privado tales como: CORFO, BIM Forum Chile, CDT (Corporaci\u00f3n de Desarrollo Tecnol\u00f3gico de la C\u00e1mara Chilena de la Construcci\u00f3n), Autodesk, Comgrap entre otros presentes en el congreso no solo de Am\u00e9rica Latina tambi\u00e9n de Reino Unido.<\/p>\n<p style=\"text-align: justify;\">Claudia Vicentelo es Ph.D. en planificaci\u00f3n territorial por la University of Illinois at Urbana-Champaign. Actualmente dirige el LAB-ICT de la Universidad de Tarapac\u00e1 y es visiting scholar en la University of Chicago en las tem\u00e1ticas de smart city y energy planning para la eficiencia de las ciudades en energ\u00eda.<\/p>\n<p style=\"text-align: justify;\">Stavros Kukulis es ingeniero civil el\u00e9ctrico por la Universidad de Tarapac\u00e1. Es project manager en el LAB-ICT y su desarrollo profesional se ha focalizado en smart energy e inteligencia de datos.<\/p>\n<p><img alt=\"Imagen foto_00000003\" border=\"0\" class=\"fotodrag\" id=\"foto_00000003\" src=\"\/web\/site\/artic\/20171214\/imag\/foto_0000000320171214184301.jpg\" style=\"display: block; margin-left: auto; margin-right: auto;\" data-w=\"550\" data-h=\"238\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CAMPLUS es la denominaci\u00f3n del \u201cPlan Maestro del Campus Saucache 2030: Ciudad del Conocimiento, Inteligente y Sostenible\u201d realizado en la Universidad de Tarapac\u00e1 y  que el comit\u00e9 cient\u00edfico de BIMLATAM seleccion\u00f3 entre las iniciativas m\u00e1s innovadoras sobre la metodolog\u00eda BIM (Building Information Modeling) en Am\u00e9rica Latina<\/p>\n","protected":false},"author":3,"featured_media":9334,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"_links":{"self":[{"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/posts\/9333"}],"collection":[{"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/comments?post=9333"}],"version-history":[{"count":0,"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/posts\/9333\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/media\/9334"}],"wp:attachment":[{"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/media?parent=9333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/categories?post=9333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/tags?post=9333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}