{"id":73969,"date":"2026-07-14T21:45:20","date_gmt":"2026-07-14T21:45:20","guid":{"rendered":"https:\/\/www.uta.cl\/?p=73969"},"modified":"2026-07-14T22:05:01","modified_gmt":"2026-07-14T22:05:01","slug":"cruch-elige-a-rector-osvaldo-corrales-como-vicepresidente-ejecutivo-2026-2028","status":"publish","type":"post","link":"https:\/\/www.uta.cl\/index.php\/2026\/07\/14\/cruch-elige-a-rector-osvaldo-corrales-como-vicepresidente-ejecutivo-2026-2028\/","title":{"rendered":"CRUCH elige a rector Osvaldo Corrales como vicepresidente ejecutivo 2026 &#8211; 2028"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/www.uta.cl\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.21.46-1024x682.jpeg\" alt=\"\" class=\"wp-image-73971\" width=\"671\" height=\"447\" srcset=\"https:\/\/www.uta.cl\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.21.46-1024x682.jpeg 1024w, https:\/\/www.uta.cl\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.21.46-300x200.jpeg 300w, https:\/\/www.uta.cl\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.21.46-768x512.jpeg 768w, https:\/\/www.uta.cl\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.21.46-1536x1023.jpeg 1536w, https:\/\/www.uta.cl\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.21.46.jpeg 1600w\" sizes=\"(max-width: 671px) 100vw, 671px\" \/><\/figure><\/div>\n\n\n\n<p>El Consejo de Rectoras y Rectores de las Universidades Chilenas (CRUCH) eligi\u00f3 por unanimidad al rector de la Universidad de Valpara\u00edso, Osvaldo Corrales Jorquera, como vicepresidente ejecutivo para el per\u00edodo 2026-2028. Asimismo, design\u00f3 a la rectora de la Universidad Cat\u00f3lica de Temuco, Marcela Momberg Alarc\u00f3n, como vicepresidenta ejecutiva alterna, convirti\u00e9ndose en la primera mujer en ejercer dicho cargo.<\/p>\n\n\n\n<p>Las decisiones fueron adoptadas durante la sesi\u00f3n plenaria N\u00b0 675 del Consejo, realizada en la Oficina Salitrera Santiago Humberstone, Patrimonio Mundial de la UNESCO, cuya organizaci\u00f3n estuvo a cargo de la Universidad Arturo Prat.<\/p>\n\n\n\n<p>El rector Osvaldo Corrales se\u00f1al\u00f3 que \u201cel CRUCH es una instituci\u00f3n muy relevante para el pa\u00eds y enfrenta muchos desaf\u00edos por lo que asumo la vicepresidencia ejecutiva con un gran sentido de responsabilidad (&#8230;) Al mismo tiempo, me parece necesario reconocer el gran trabajo realizado por el rector Emilio Rodr\u00edguez durante los \u00faltimos cuatro a\u00f1os, proyectando el trabajo del CRUCH en diversos \u00e1mbitos\u201d.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/www.uta.cl\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-18.03.14-1024x576.jpeg\" alt=\"\" class=\"wp-image-73975\" width=\"607\" height=\"341\" srcset=\"https:\/\/www.uta.cl\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-18.03.14-1024x576.jpeg 1024w, https:\/\/www.uta.cl\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-18.03.14-300x169.jpeg 300w, https:\/\/www.uta.cl\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-18.03.14-768x432.jpeg 768w, https:\/\/www.uta.cl\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-18.03.14.jpeg 1280w\" sizes=\"(max-width: 607px) 100vw, 607px\" \/><\/figure><\/div>\n\n\n\n<p>En cuanto a los desaf\u00edos para los pr\u00f3ximos a\u00f1os, el rector Corrales identific\u00f3 la formaci\u00f3n de profesoras y profesores, el reemplazo del CAE por un sistema de financiamiento justo y sostenible, la duraci\u00f3n de las carreras y la pertinencia de la formaci\u00f3n, as\u00ed como el impacto de la inteligencia artificial en la educaci\u00f3n superior.<\/p>\n\n\n\n<p>Ciertamente en los pr\u00f3ximos a\u00f1os nos corresponder\u00e1 discutir temas de la mayor importancia para el futuro de la educaci\u00f3n superior como el financiamiento del sistema y la duraci\u00f3n de carreras, entre otros desaf\u00edos para la educaci\u00f3n superior\u201d.<\/p>\n\n\n\n<p>Por su parte, la rectora Marcela Momberg sostuvo que su elecci\u00f3n constituye un reconocimiento importante que evidencia \u201cun cambio significativo en nuestra sociedad y en el sistema de educaci\u00f3n superior. Mi nombramiento, por unanimidad, es un signo de aprecio por el trabajo realizado y por el resto de las rectoras que integramos el Consejo. Tambi\u00e9n reconoce a todas las acad\u00e9micas, funcionarias y estudiantes de nuestras universidades\u201d.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/www.uta.cl\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.21.46-1-1024x682.jpeg\" alt=\"\" class=\"wp-image-73970\" width=\"550\" height=\"366\" srcset=\"https:\/\/www.uta.cl\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.21.46-1-1024x682.jpeg 1024w, https:\/\/www.uta.cl\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.21.46-1-300x200.jpeg 300w, https:\/\/www.uta.cl\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.21.46-1-768x512.jpeg 768w, https:\/\/www.uta.cl\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.21.46-1-1536x1023.jpeg 1536w, https:\/\/www.uta.cl\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.21.46-1.jpeg 1600w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/figure><\/div>\n\n\n\n<p>El pleno tambi\u00e9n defini\u00f3 la conformaci\u00f3n del Comit\u00e9 Ejecutivo del CRUCH para el pr\u00f3ximo per\u00edodo, que qued\u00f3 integrado por la rectora de la Universidad Tecnol\u00f3gica Metropolitana, Marisol Dur\u00e1n Santis, en su calidad de presidenta del Consorcio de Universidades del Estado de Chile (CUECH); el rector de la Pontificia Universidad Cat\u00f3lica de Chile, Juan Carlos de la Llera, presidente de la Red de Universidades P\u00fablicas no Estatales (G9); y el rector de la Universidad Cat\u00f3lica del Maule, Claudio Rojas Mi\u00f1o, presidente de la Agrupaci\u00f3n de Universidades Regionales (AUR).<\/p>\n\n\n\n<p>Adem\u00e1s, integrar\u00e1n esta instancia el rector de la Universidad Arturo Prat, Alberto Mart\u00ednez Quezada (CUECH); la rectora de la Universidad Cat\u00f3lica del Norte, Mar\u00eda Cecilia Hern\u00e1ndez Vera (G9); y el rector de la Universidad Alberto Hurtado, Cristi\u00e1n del Campo Simonetti SJ, representante de las universidades incorporadas al CRUCH conforme a la Ley N\u00b0 21.091.<\/p>\n\n\n\n<p>El Comit\u00e9 Ejecutivo tiene entre sus principales funciones dirigir el trabajo del Consejo entre las sesiones plenarias, coordinar la relaci\u00f3n institucional con el Ministerio de Educaci\u00f3n y otros organismos p\u00fablicos, y supervisar el desarrollo de iniciativas y proyectos impulsados por el CRUCH.<\/p>\n\n\n\n<h2><strong>Reconocimiento CRUCH 2026<\/strong><\/h2>\n\n\n\n<p>En la misma sesi\u00f3n, el pleno aprob\u00f3 por unanimidad otorgar el Reconocimiento CRUCH a la Contribuci\u00f3n en Educaci\u00f3n Superior 2026 al exrector de la Universidad de Talca, \u00c1lvaro Rojas Mar\u00edn. La distinci\u00f3n ser\u00e1 entregada durante agosto, en el marco de las actividades conmemorativas por el 72\u00b0 aniversario del Consejo.<\/p>\n\n\n\n<p>La presidenta del Comit\u00e9 de Concurso y rectora de la Universidad de La Serena, Luperfina Rojas Escobar, destac\u00f3 que \u201cla trayectoria de \u00c1lvaro Rojas representa los valores de este reconocimiento: visi\u00f3n de futuro, capacidad transformadora y un compromiso permanente con la educaci\u00f3n p\u00fablica y el desarrollo de las regiones y el pa\u00eds\u201d.<\/p>\n\n\n\n<p>Creado en 2024, el Reconocimiento CRUCH distingue cada dos a\u00f1os a personas cuya trayectoria haya realizado un aporte significativo al desarrollo del sistema de educaci\u00f3n superior chileno.<\/p>\n\n\n\n<h2><strong>Pleno reconoce la gesti\u00f3n de Emilio Rodr\u00edguez<\/strong><\/h2>\n\n\n\n<p>La sesi\u00f3n plenaria marc\u00f3 el t\u00e9rmino del per\u00edodo del rector de la Universidad de Tarapac\u00e1, Emilio Rodr\u00edguez Ponce, como vicepresidente ejecutivo del CRUCH, cargo que desempe\u00f1\u00f3 durante cuatro a\u00f1os.<\/p>\n\n\n\n<p>En la oportunidad, rectoras y rectores reconocieron su gesti\u00f3n y su aporte al fortalecimiento del trabajo colaborativo impulsado por el Consejo durante ese per\u00edodo.<\/p>\n\n\n\n<p>La subsecretaria de Educaci\u00f3n Superior, Fernanda Vald\u00e9s Raczynski, destac\u00f3 el legado de Emilio Rodr\u00edguez. \u201cCon su juicio ponderado ha dado una cohesi\u00f3n al Consejo de Rectores que no ten\u00eda antes, y ha sido capaz de abordar los temas en profundidad con su conocimiento, con su experiencia acad\u00e9mica y disciplinar, y, al mismo tiempo, muy abierto a distintos requerimientos que le han hecho las distintas instituciones (&#8230;), por lo tanto, su gesti\u00f3n es dif\u00edcil de igualar, porque, en realidad, re\u00fane muchas caracter\u00edsticas con las cuales estamos muy agradecidos\u201d, coment\u00f3.<\/p>\n\n\n\n<p>Finalmente, el pleno tambi\u00e9n reconoci\u00f3 al rector de la Universidad de Antofagasta, Marcos Cikutovic, quien dejar\u00e1 el cargo el pr\u00f3ximo 21 de agosto tras concluir su per\u00edodo al frente de esa casa de estudios.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/www.uta.cl\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.21.45-1-1024x682.jpeg\" alt=\"\" class=\"wp-image-73972\" width=\"546\" height=\"363\" srcset=\"https:\/\/www.uta.cl\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.21.45-1-1024x682.jpeg 1024w, https:\/\/www.uta.cl\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.21.45-1-300x200.jpeg 300w, https:\/\/www.uta.cl\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.21.45-1-768x512.jpeg 768w, https:\/\/www.uta.cl\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.21.45-1-1536x1023.jpeg 1536w, https:\/\/www.uta.cl\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.21.45-1.jpeg 1600w\" sizes=\"(max-width: 546px) 100vw, 546px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Durante la sesi\u00f3n se reconoci\u00f3 la gesti\u00f3n del vicepresidente ejecutivo saliente, Emilio Rodr\u00edguez, y se aprob\u00f3 por unanimidad que el exrector de la Universidad de Talca, \u00c1lvaro Rojas Mar\u00edn, reciba el Reconocimiento CRUCH a la Contribuci\u00f3n en Educaci\u00f3n Superior 2026.<\/p>\n","protected":false},"author":13,"featured_media":73971,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[315,316],"tags":[],"_links":{"self":[{"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/posts\/73969"}],"collection":[{"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/comments?post=73969"}],"version-history":[{"count":2,"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/posts\/73969\/revisions"}],"predecessor-version":[{"id":73977,"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/posts\/73969\/revisions\/73977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/media\/73971"}],"wp:attachment":[{"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/media?parent=73969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/categories?post=73969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/tags?post=73969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}