{"id":11757,"date":"2018-01-08T18:02:50","date_gmt":"2018-01-08T18:02:50","guid":{"rendered":"https:\/\/www.uta.cl\/facultad-de-educacion-y-humanidades-realizo-claustro-academico\/web\/2018-01-08\/180250.html"},"modified":"2018-01-08T18:02:50","modified_gmt":"2018-01-08T18:02:50","slug":"facultad-de-educacion-y-humanidades-realizo-claustro-academico","status":"publish","type":"post","link":"https:\/\/www.uta.cl\/index.php\/2018\/01\/08\/facultad-de-educacion-y-humanidades-realizo-claustro-academico\/","title":{"rendered":"Facultad de Educaci\u00f3n y Humanidades realiz\u00f3 claustro acad\u00e9mico"},"content":{"rendered":"\n<p style=\"text-align: justify;\"><img loading=\"lazy\" alt=\"Imagen foto_00000003\" class=\"fotodrag\" height=\"295\" id=\"foto_00000003\" src=\"\/web\/site\/artic\/20180108\/imag\/foto_0000000320180108180250.jpg\" style=\"margin-left: 10px; margin-right: 10px; float: left;\" width=\"458\" data-w=\"800\" data-h=\"518\" \/>La actividad, celebrada el viernes 5 de enero, cont\u00f3 con la participaci\u00f3n del decano, doctor Jorge Lagos Caama\u00f1o; de los directores de departamento, de Espa\u00f1ol, Ingrid Guill\u00e9n Figueroa; de Idiomas Extranjeros, Jaime G\u00f3mez Douzet; de Educaci\u00f3n, Mario B\u00e1ez Estradas; de Ciencias Hist\u00f3ricas y Geogr\u00e1ficas, Alejandro Tapia Tosetti; y de Ciencias de la Actividad F\u00edsica y del Deporte, Osm\u00e1n Ponce Farf\u00e1n; de los jefes de carrera y docentes.<\/p>\n<p style=\"text-align: justify;\">En primer t\u00e9rmino, el decano ofreci\u00f3 su saludo y dio a conocer el contexto del claustro acad\u00e9mico. Se\u00f1al\u00f3 que &#8220;la actividad surgi\u00f3 a proposici\u00f3n del consejo de facultad, quien encontr\u00f3 necesario examinar y discutir algunos temas que se derivaban del Modelo Educativo Institucional y de los Modelos Pedag\u00f3gicos Institucional y de unidad&#8221;.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" alt=\"Imagen foto_00000002\" class=\"fotodrag\" height=\"240\" id=\"foto_00000002\" src=\"\/web\/site\/artic\/20180108\/imag\/foto_0000000220180108180250.jpg\" style=\"float: left; margin-left: 10px; margin-right: 10px;\" width=\"180\" data-w=\"800\" data-h=\"1067\" \/>En segundo lugar, la expresi\u00f3n del Ministerio de Educaci\u00f3n (MINEDUC) a trav\u00e9s del Centro de Perfeccionamiento, Experimentaci\u00f3n e Investigaciones Pedag\u00f3gicas (CPEIP) durante 2017, de &#8220;resaltar la necesidad de incrementar la investigaci\u00f3n aplicada en pedagog\u00eda&#8221;. Tambi\u00e9n, la necesidad &#8220;de reflexionar como Facultad de Educaci\u00f3n y Humanidades sobre la percepci\u00f3n que se tiene respecto de la incipiencia, exig\u00fcedad y calidad de las investigaciones en el \u00e1mbito educativo en comparaci\u00f3n a las que se realizan en otras \u00e1reas disciplinarias&#8221;.<\/p>\n<p style=\"text-align: justify;\">Por \u00faltimo, como somos una facultad que re\u00fane diferentes disciplinas human\u00edsticas que se relacionan con el \u00e1rea educacional al sostener la mayor parte de las carreras de pedagog\u00eda de la Universidad de Tarapac\u00e1, &#8220;reflexionar sobre los eventuales aportes disciplinarios a la investigaci\u00f3n pedag\u00f3gica y viceversa&#8221;. El &#8220;porqu\u00e9 o para qu\u00e9 realizar este ejercicio intelectual es uno de los aspectos sobre el cual discutiremos en este claustro&#8221;, dijo el decano Lagos Caama\u00f1o.<\/p>\n<p style=\"text-align: justify;\"><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" alt=\"Imagen foto_00000004\" class=\"fotodrag\" height=\"240\" id=\"foto_00000004\" src=\"\/web\/site\/artic\/20180108\/imag\/foto_0000000420180108180250.jpg\" style=\"margin-left: 10px; margin-right: 10px; float: left;\" width=\"180\" data-w=\"800\" data-h=\"1067\" \/>La exposici\u00f3n estuvo a cargo del doctor Carlos Calvo Mu\u00f1oz, Ph. D. en Antropolog\u00eda Educacional por Stanford University, USA; acad\u00e9mico postdoctoral en las universidades de Stanford y Lovaina, B\u00e9lgica; y &#8216;trainer&#8217; en el Programa de Enriquecimiento Instrumental (PEI) (Desarrollo Cognitivo en el \u00c1mbito Educativo), en Hadassah Wiso Research Institute de Jerusalem, Israel. En Chile, profesor titular de la Universidad de La Serena; director del programa de doctorado en Educaci\u00f3n con menci\u00f3n en mediaci\u00f3n pedag\u00f3gica de la misma universidad; investigador principal y coinvestigador de proyectos para el Fondo Nacional Cient\u00edfico y Tecnol\u00f3gico (FONDECYT); autor de libros y de cap\u00edtulos de libros con arbitraje y comit\u00e9 editorial; y autor de art\u00edculos incorporados en revistas cient\u00edficas o de corriente principal.<\/p>\n<p style=\"text-align: justify;\">Luego de la exposici\u00f3n, los acad\u00e9micos se agruparon para reflexionar sobre las siguientes interrogantes: \u00bfel estado del arte de la investigaci\u00f3n en educaci\u00f3n en la facultad?, \u00bfc\u00f3mo ha sido la experiencia en investigaci\u00f3n disciplinaria en la FEH?, \u00bfc\u00f3mo las disciplinas pueden aportar a la investigaci\u00f3n pedag\u00f3gica, tanto te\u00f3rica como aplicada?, \u00bfmetodolog\u00eda o did\u00e1ctica de la ense\u00f1anza disciplinar?, \u00bfde qu\u00e9 hablamos cuando nos referimos a did\u00e1ctica?, \u00bfc\u00f3mo se logra que la disciplina fortalezca la investigaci\u00f3n pedag\u00f3gica, te\u00f3rica y aplicada?, \u00bfes necesaria la investigaci\u00f3n pedag\u00f3gica aplicada para realizar cambios efectivos en la educaci\u00f3n chilena?, y \u00bfc\u00f3mo podr\u00eda la investigaci\u00f3n pedag\u00f3gica aplicada asegurar la eficacia de los m\u00e9todos de ense\u00f1anza-aprendizaje for\u00e1neas implementadas en Chile?<\/p>\n<p style=\"text-align: justify;\">De acuerdo con las opiniones de la mayor parte de los acad\u00e9micos de la FEH, la presencia del Doctor Carlos Calvo Mu\u00f1oz -en el primer claustro acad\u00e9mico 2018- logr\u00f3 sus prop\u00f3sitos: hacernos reflexionar sobre la g\u00e9nesis y procesos de elaboraci\u00f3n de los modelos de desarrollo educativo; la investigaci\u00f3n pedag\u00f3gica y las discordancias intr\u00ednsecas existentes en el sistema educacional.<\/p>\n<p style=\"text-align: justify;\">Asimismo, otro aspecto relevante del claustro inferido de la exposici\u00f3n del Dr. Calvo Mu\u00f1oz y del taller realizado, tuvo relaci\u00f3n con devolvernos la expectativa de que es posible realizar la labor docente desde el amor, desde el candor humano, la inclusi\u00f3n y la est\u00e9tica pedag\u00f3gica m\u00e1s all\u00e1 de los tecnicismos y de lo cuantificable.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bajo el tema central \u201cSistemas de desarrollo educativo e investigaci\u00f3n pedag\u00f3gica aplicada\u201d, los docentes de la Facultad de Educaci\u00f3n y Humanidades (FEH) de la Universidad de Tarapac\u00e1 (UTA) reflexionaron en el primer claustro acad\u00e9mico de 2018.  <\/p>\n","protected":false},"author":3,"featured_media":11758,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"_links":{"self":[{"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/posts\/11757"}],"collection":[{"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/comments?post=11757"}],"version-history":[{"count":0,"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/posts\/11757\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/media\/11758"}],"wp:attachment":[{"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/media?parent=11757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/categories?post=11757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/tags?post=11757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}