{"id":11723,"date":"2018-01-17T15:34:22","date_gmt":"2018-01-17T15:34:22","guid":{"rendered":"https:\/\/www.uta.cl\/s\/jEY"},"modified":"2018-01-17T15:34:22","modified_gmt":"2018-01-17T15:34:22","slug":"academicos-de-la-uta-se-capacitan-en-el-uso-del-modelo-de-ensenanza","status":"publish","type":"post","link":"https:\/\/www.uta.cl\/index.php\/2018\/01\/17\/academicos-de-la-uta-se-capacitan-en-el-uso-del-modelo-de-ensenanza\/","title":{"rendered":"Acad\u00e9micos de la UTA se capacitan en el uso del modelo de ense\u00f1anza \u201cFlipped Classroom\u201d"},"content":{"rendered":"\n<p style=\"text-align: justify;\"><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" alt=\"Imagen foto_00000002\" class=\"fotodrag\" height=\"232\" id=\"foto_00000002\" src=\"\/web\/site\/artic\/20180117\/imag\/foto_0000000220180117153422.jpg\" style=\"float: left; margin-left: 10px; margin-right: 10px;\" width=\"349\" data-w=\"600\" data-h=\"400\" \/><\/p>\n<p style=\"text-align: justify;\">En el marco del desarrollo de la \u201cEscuela de perfeccionamiento docente entre pares\u201d, del Convenio de Desempe\u00f1o de Armonizaci\u00f3n Curricular UTA 1501, acad\u00e9micos de las distintas facultades y escuelas de la Universidad de Tarapac\u00e1, asistieron al curso \u201cFlipped Classroom\u201d o clase invertida. Taller que fue llevado a cabo por el acad\u00e9mico del Departamento de Educaci\u00f3n, Rub\u00e9n Capetillo Vel\u00e1squez.<br \/><br \/>El curso, que consisti\u00f3 en dos sesiones m\u00e1s la entrega de un trabajo final online, cont\u00f3 con la asistencia masiva de acad\u00e9micos interesados por mejorar sus pr\u00e1cticas docentes. Adem\u00e1s, recibi\u00f3 la visita de una delegaci\u00f3n de la Universidad Mayor de San Andr\u00e9s, Bolivia, quienes, enterados a trav\u00e9s de la Direcci\u00f3n de Asuntos Interinstitucionales e Internacionales, se hicieron presentes para participar.<br \/><br \/>DANDO VUELTA EL AULA<br \/>The Flipped Classroom o la clase al rev\u00e9s, es un modelo pedag\u00f3gico que transfiere el trabajo de determinados procesos de aprendizaje fuera del aula y utiliza el tiempo de clase, junto con la experiencia del docente, para facilitar y potenciar otros procesos de adquisici\u00f3n y pr\u00e1ctica de conocimientos dentro del aula. As\u00ed, la clase al rev\u00e9s permite personalizar el aprendizaje, ya que el contenido b\u00e1sico es estudiado en casa con materiales aportados por el profesor mientras que el tiempo de clase se invierte en crear, a trav\u00e9s de la pr\u00e1ctica, reflexionar y comprender de manera formativa e individualizada para cada estudiante.<br \/><br \/>En definitiva, Flipped Classroom no es una herramienta ni una tecnolog\u00eda, sino un modo de trabajo con los estudiantes que facilita su aprendizaje de un modo personalizado, es decir, el centro del aprendizaje es siempre el alumno con sus necesidades y no las herramientas o los conocimientos.<br \/><br \/><\/p>\n<p style=\"text-align: justify;\"><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" alt=\"Imagen foto_00000001\" class=\"fotodrag\" height=\"234\" id=\"foto_00000001\" src=\"\/web\/site\/artic\/20180117\/imag\/foto_0000000120180117153422.jpg\" style=\"float: left; margin-left: 10px; margin-right: 10px;\" width=\"350\" data-w=\"600\" data-h=\"400\" \/><\/p>\n<p style=\"text-align: justify;\">REACCIONES<br \/>Rub\u00e9n Capetillo, acad\u00e9mico a cargo de la realizaci\u00f3n del taller, manifest\u00f3 su satisfacci\u00f3n por el buen desarrollo de la actividad. Tambi\u00e9n destac\u00f3 la gran asistencia y la entrega de los asistentes para aprender, conocer e innovar en los procesos de ense\u00f1anza-aprendizaje, lo que, a su juicio, demuestra el gran inter\u00e9s de los acad\u00e9micos de la UTA.  Asimismo, precis\u00f3 que la innovaci\u00f3n en docencia superior es vital, porque de otra forma no se podr\u00e1 alcanzar lo que propone el Modelo Educativo Institucional. <br \/><br \/>En relaci\u00f3n a la participaci\u00f3n de los acad\u00e9micos presentes, se\u00f1al\u00f3 que fue muy activa. \u201cEste modelo no termina cuando la clase finaliza y este caso no ser\u00e1 excepci\u00f3n, nosotros vamos a seguir conectados, ya que ese es el fin, que el aprendizaje sea continuo\u201d, detall\u00f3.<br \/><br \/>Mientras, que Jaime Silva, acad\u00e9mico del Departamento de Kinesiolog\u00eda y Nutrici\u00f3n, valor\u00f3 la instancia, destacando el manejo y conocimiento sobre el tema que tiene el profesor Capetillo. Sobre lo mismo, indic\u00f3 que el taller le permiti\u00f3 conocer un modelo y herramientas que facilitan el desarrollo de la academia. \u201cSi bien, siento que fue poco el tiempo, creo que ha sido un gran aporte este taller, va a quedar en cada uno de nosotros seguir investigando e introducirnos en esta tem\u00e1tica y en otras m\u00e1s por supuesto\u201d, expres\u00f3. <br \/><br \/>Por otra parte, el acad\u00e9mico de FACSAL, coment\u00f3 que participar de estas instancias, contribuye a la reflexi\u00f3n docente. \u201cNos permite darnos una pausa y revisar nuestros procesos y resultados\u201d, apunt\u00f3.<br \/><br \/>En tanto, Oscar Machaca Condori, profesional de la Facultad de Derecho y Ciencias Pol\u00edticas de la Universidad Mayor San Andr\u00e9s de la Paz, Bolivia, cont\u00f3 que su visita, se debe principalmente a la necesidad de actualizarse y continuar con un acuerdo de colaboraci\u00f3n mutua, tecnol\u00f3gica, acad\u00e9mica y cient\u00edfica entre la UTA y la UMSA.  Respecto al taller, Machaca se mostr\u00f3 sorprendido con este modelo que permite optimizar las clases y con la aplicaci\u00f3n de las TIC, que da al estudiante la oportunidad de ser su principal agente activo en el proceso de ense\u00f1anza-aprendizaje.<br \/><br \/>\u201cAgradezco la invitaci\u00f3n y al profesor Capetillo, por sus ense\u00f1anzas, all\u00e1 en Bolivia no se conoce este modelo, y lo vamos a poner en pr\u00e1ctica sin dudas\u201d, sostuvo el acad\u00e9mico de la UMSA, que adem\u00e1s coment\u00f3 que el grupo de lo acompa\u00f1a se compone de estudiantes egresados del \u00e1rea de docencia, quienes seg\u00fan coment\u00f3, se encuentran muy motivados en aprender, se\u00f1al\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Modelo utiliza herramientas tecnol\u00f3gicas que contribuyen al aprendizaje aut\u00f3nomo.<\/p>\n","protected":false},"author":3,"featured_media":11724,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"_links":{"self":[{"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/posts\/11723"}],"collection":[{"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/comments?post=11723"}],"version-history":[{"count":0,"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/posts\/11723\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/media\/11724"}],"wp:attachment":[{"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/media?parent=11723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/categories?post=11723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uta.cl\/index.php\/wp-json\/wp\/v2\/tags?post=11723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}